{"id":5,"count":3,"description":"","link":"https:\/\/acadifyos.com\/blog\/academy-operations\/","name":"Operations &amp; Staff Management","slug":"academy-operations","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/acadifyos.com\/blog\/wp-json\/wp\/v2\/categories\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acadifyos.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/acadifyos.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/acadifyos.com\/blog\/wp-json\/wp\/v2\/posts?categories=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}